{"id":171,"count":2,"description":"","link":"https:\/\/www.presasg8.es\/pt-pt\/categoria\/treinamento\/romos-para-o-campus\/","name":"Romos para o campus","slug":"romos-para-o-campus","taxonomy":"product_cat","parent":116,"meta":[],"menu_order":5,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Romos para o campus archivos - Presas G8 - Presas de escalada para roc\u00f3dromo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.presasg8.es\/pt-pt\/categoria\/treinamento\/romos-para-o-campus\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Romos para o campus archivos - Presas G8 - Presas de escalada para roc\u00f3dromo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.presasg8.es\/pt-pt\/categoria\/treinamento\/romos-para-o-campus\/\" \/>\n<meta property=\"og:site_name\" content=\"Presas G8 - Presas de escalada para roc\u00f3dromo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.presasg8.es\\\/pt-pt\\\/categoria\\\/treinamento\\\/romos-para-o-campus\\\/\",\"url\":\"https:\\\/\\\/www.presasg8.es\\\/pt-pt\\\/categoria\\\/treinamento\\\/romos-para-o-campus\\\/\",\"name\":\"Romos para o campus archivos - Presas G8 - Presas de escalada para roc\u00f3dromo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.presasg8.es\\\/pt-pt\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.presasg8.es\\\/pt-pt\\\/categoria\\\/treinamento\\\/romos-para-o-campus\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.presasg8.es\\\/pt-pt\\\/categoria\\\/treinamento\\\/romos-para-o-campus\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.presasg8.es\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Treinamento\",\"item\":\"https:\\\/\\\/www.presasg8.es\\\/pt-pt\\\/categoria\\\/treinamento\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Romos para o campus\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.presasg8.es\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/www.presasg8.es\\\/pt-pt\\\/\",\"name\":\"Presas de escalada G8\",\"description\":\"Tienda online de Presas de escalada para roc\u00f3dromo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.presasg8.es\\\/pt-pt\\\/#organization\"},\"alternateName\":\"Presas de escalada para roc\u00f3dromo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.presasg8.es\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.presasg8.es\\\/pt-pt\\\/#organization\",\"name\":\"Presas de escalada G8\",\"alternateName\":\"Presas de escalada para roc\u00f3dromo G8\",\"url\":\"https:\\\/\\\/www.presasg8.es\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.presasg8.es\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.presasg8.es\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/logo-presas-g8.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.presasg8.es\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/logo-presas-g8.jpeg\",\"width\":400,\"height\":486,\"caption\":\"Presas de escalada G8\"},\"image\":{\"@id\":\"https:\\\/\\\/www.presasg8.es\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/presasescaladag8\\\/\",\"https:\\\/\\\/www.instagram.com\\\/presasg8\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Romos para o campus archivos - Presas G8 - Presas de escalada para roc\u00f3dromo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.presasg8.es\/pt-pt\/categoria\/treinamento\/romos-para-o-campus\/","og_locale":"pt_PT","og_type":"article","og_title":"Romos para o campus archivos - Presas G8 - Presas de escalada para roc\u00f3dromo","og_url":"https:\/\/www.presasg8.es\/pt-pt\/categoria\/treinamento\/romos-para-o-campus\/","og_site_name":"Presas G8 - Presas de escalada para roc\u00f3dromo","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.presasg8.es\/pt-pt\/categoria\/treinamento\/romos-para-o-campus\/","url":"https:\/\/www.presasg8.es\/pt-pt\/categoria\/treinamento\/romos-para-o-campus\/","name":"Romos para o campus archivos - Presas G8 - Presas de escalada para roc\u00f3dromo","isPartOf":{"@id":"https:\/\/www.presasg8.es\/pt-pt\/#website"},"breadcrumb":{"@id":"https:\/\/www.presasg8.es\/pt-pt\/categoria\/treinamento\/romos-para-o-campus\/#breadcrumb"},"inLanguage":"pt-PT"},{"@type":"BreadcrumbList","@id":"https:\/\/www.presasg8.es\/pt-pt\/categoria\/treinamento\/romos-para-o-campus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.presasg8.es\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Treinamento","item":"https:\/\/www.presasg8.es\/pt-pt\/categoria\/treinamento\/"},{"@type":"ListItem","position":3,"name":"Romos para o campus"}]},{"@type":"WebSite","@id":"https:\/\/www.presasg8.es\/pt-pt\/#website","url":"https:\/\/www.presasg8.es\/pt-pt\/","name":"Presas de escalada G8","description":"Tienda online de Presas de escalada para roc\u00f3dromo","publisher":{"@id":"https:\/\/www.presasg8.es\/pt-pt\/#organization"},"alternateName":"Presas de escalada para roc\u00f3dromo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.presasg8.es\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.presasg8.es\/pt-pt\/#organization","name":"Presas de escalada G8","alternateName":"Presas de escalada para roc\u00f3dromo G8","url":"https:\/\/www.presasg8.es\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.presasg8.es\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/www.presasg8.es\/wp-content\/uploads\/2023\/09\/logo-presas-g8.jpeg","contentUrl":"https:\/\/www.presasg8.es\/wp-content\/uploads\/2023\/09\/logo-presas-g8.jpeg","width":400,"height":486,"caption":"Presas de escalada G8"},"image":{"@id":"https:\/\/www.presasg8.es\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/presasescaladag8\/","https:\/\/www.instagram.com\/presasg8\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.presasg8.es\/pt-pt\/wp-json\/wp\/v2\/product_cat\/171","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.presasg8.es\/pt-pt\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.presasg8.es\/pt-pt\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/www.presasg8.es\/pt-pt\/wp-json\/wp\/v2\/product_cat\/116"}],"wp:post_type":[{"href":"https:\/\/www.presasg8.es\/pt-pt\/wp-json\/wp\/v2\/product?product_cat=171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}